{"id":4069,"date":"2024-09-23T00:57:01","date_gmt":"2024-09-23T00:57:01","guid":{"rendered":"https:\/\/bolivianoticia.com\/index.php\/2024\/09\/23\/ypfb-introduce-al-mercado-nueva-gasolina-ultra-premium-100\/"},"modified":"2024-09-23T00:57:01","modified_gmt":"2024-09-23T00:57:01","slug":"ypfb-introduce-al-mercado-nueva-gasolina-ultra-premium-100","status":"publish","type":"post","link":"https:\/\/bolivianoticia.com\/index.php\/2024\/09\/23\/ypfb-introduce-al-mercado-nueva-gasolina-ultra-premium-100\/","title":{"rendered":"YPFB introduce al mercado nueva \u201cGasolina Ultra Premium 100\u201d"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Desde este s\u00e1bado, Yacimientos Petrol\u00edferos Fiscales Bolivianos (YPFB) comercializa en el mercado la Gasolina Ultra Premium 100, combustible que mejora el rendimiento de los motores y proporciona una mayor potencia, inform\u00f3 el presidente de YPFB, Armin Dorgathen Tapia.<\/p>\n<p>\u201cHemos introducido al mercado esta nueva gasolina de alto octanaje. El producto mejora el rendimiento de los motores y proporciona mayor potencia a los veh\u00edculos. Se recorrer\u00e1 una mayor cantidad de kil\u00f3metros con una menor cantidad de este combustible, situaci\u00f3n que posibilitar\u00e1 un ahorro al consumidor\u201d, destac\u00f3 Dorgathen Tapia durante el acto de lanzamiento de este producto realizado en la estaci\u00f3n de servicio El Pari, junto a representantes del automovilismo nacional.\u00a0<\/p>\n<p>El nuevo combustible tiene un octanaje m\u00ednimo de RON 99 hasta RON 100 y se formula y\/o produce a partir de la proporci\u00f3n de 88% de una Gasolina Base y la mezcla con 12% de etanol anhidro. \u201cEl litro de esta gasolina tiene un costo de Bs 6,71 el mismo fluctuar\u00e1 de acuerdo a la variaci\u00f3n del precio internacional del petr\u00f3leo. Este combustible es amigable con el medio ambiente y cumple con la normativa internacional EURO\u201d, manifest\u00f3 Joel Calla\u00fa Justiniano, gerente de Comercializaci\u00f3n de YPFB.\u00a0<\/p>\n<p>l nuevo producto est\u00e1 destinado al parque automotor de veh\u00edculos de alta gama importados desde la gesti\u00f3n 2021, asimismo para veh\u00edculos destinados a carreras automovil\u00edsticas que anteriormente utilizaban gasolinas de aviaci\u00f3n para obtener la potencia necesaria. Los veh\u00edculos que ser\u00edan objetivo se proyectan entre 61.818 a 125.409 entre camionetas, veh\u00edculos utilitarios deportivos (SUV, por sus siglas en ingl\u00e9s) y autom\u00f3viles. Inicialmente se comercializar\u00e1 el producto en aproximadamente 15 estaciones de servicio de La Paz y Santa Cruz, para posteriormente expandirse a Cochabamba y el resto del pa\u00eds.<\/p>\n<h2><strong>VENTAJAS<\/strong><\/h2>\n<p>Con el incremento en el octanaje hasta RON 100, el rendimiento del motor ser\u00e1 considerable y podr\u00e1 recorrer una mayor cantidad de kil\u00f3metros con una menor cantidad de combustible. La nueva gasolina cuida el medio ambiente por la reducci\u00f3n en la contaminaci\u00f3n por la mezcla con el etanol anhidro. Nivela los precios de mercado con los pa\u00edses lim\u00edtrofes, para frenar el contrabando de combustibles.<\/p>\n<p>Adem\u00e1s, reduce la subvenci\u00f3n para el pa\u00eds por la importaci\u00f3n de gasolinas. Por el uso de etanol de origen nacional en la formulaci\u00f3n de esta gasolina se reduce la fuga de divisas y contribuye a la econom\u00eda del Estado.<\/p>\n<h2><strong>GASOLINA PREMIUM +<\/strong><\/h2>\n<p>Este combustible se comercializa a Bs 5,71 el litro, precio que podr\u00e1 ser modificado de acuerdo a las variaciones del precio internacional del petr\u00f3leo crudo. El combustible tiene un octanaje de RON 95. Se formula y\/o produce a partir de una proporci\u00f3n de Gasolina Base (RON 91) y 12% de etanol anhidro. Actualmente, se comercializa en 55 estaciones de servicio de los departamentos de Santa Cruz, La Paz y Cochabamba.<\/p>\n<p>La Gasolina Premium + est\u00e1 orientada a satisfacer la demanda de veh\u00edculos modernos, tanto de pasajeros como de carga, y contribuye a diversificar la gama de productos en el mercado interno.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.opinion.com.bo\/articulo\/pais\/ypfb-introduce-mercado-nueva-gasolina-ultra-premium-100\/20240922172037956281.html\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde este s\u00e1bado, Yacimientos Petrol\u00edferos Fiscales Bolivianos (YPFB) comercializa en el mercado la Gasolina Ultra Premium 100, combustible que mejora el rendimiento de los motores y proporciona una mayor potencia, inform\u00f3 el presidente de YPFB, Armin Dorgathen Tapia. \u201cHemos introducido al mercado esta nueva gasolina de alto octanaje. El producto mejora el rendimiento de los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4070,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4069","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/bolivianoticia.com\/index.php\/wp-json\/wp\/v2\/posts\/4069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bolivianoticia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bolivianoticia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bolivianoticia.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bolivianoticia.com\/index.php\/wp-json\/wp\/v2\/comments?post=4069"}],"version-history":[{"count":0,"href":"https:\/\/bolivianoticia.com\/index.php\/wp-json\/wp\/v2\/posts\/4069\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bolivianoticia.com\/index.php\/wp-json\/wp\/v2\/media\/4070"}],"wp:attachment":[{"href":"https:\/\/bolivianoticia.com\/index.php\/wp-json\/wp\/v2\/media?parent=4069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bolivianoticia.com\/index.php\/wp-json\/wp\/v2\/categories?post=4069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bolivianoticia.com\/index.php\/wp-json\/wp\/v2\/tags?post=4069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}