{"id":4061,"date":"2024-09-22T06:00:14","date_gmt":"2024-09-22T06:00:14","guid":{"rendered":"https:\/\/bolivianoticia.com\/index.php\/2024\/09\/22\/de-mentor-pupilo-a-una-rina-de-2-anos\/"},"modified":"2024-09-22T06:00:14","modified_gmt":"2024-09-22T06:00:14","slug":"de-mentor-pupilo-a-una-rina-de-2-anos","status":"publish","type":"post","link":"https:\/\/bolivianoticia.com\/index.php\/2024\/09\/22\/de-mentor-pupilo-a-una-rina-de-2-anos\/","title":{"rendered":"de mentor-pupilo a una ri\u00f1a de 2 a\u00f1os"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>En julio de 2022, los rumores tomaban cierta fuerza: las rencillas entre el jefe de Estado, Luis Arce, y quien lo escogi\u00f3 entre sus hombres para que fuera su \u201csucesor\u201d, Evo Morales, ya exist\u00edan, aunque no se ventilaban medi\u00e1ticamente. Sin embargo, el excocalero se apresuraba para intentar derribar las teor\u00edas que apuntaban a sacar sobre la superficie las diferencias internas. En uno de sus intentos por convencer de que las aguas estaban serenas en el Movimiento Al Socialismo (MAS), dec\u00eda, en entrevista con el diario P\u00e1gina 12 de Argentina: \u201cNo hay ninguna divisi\u00f3n. A Lucho le corresponde la administraci\u00f3n del Estado, dirigir Bolivia, y a m\u00ed me corresponde dirigir el movimiento pol\u00edtico\u2026 y juntos. No faltan algunos problemas, es normal eso\u201d.<\/p>\n<p>Pero tal parece que dicho discurso no podr\u00eda ser sostenido por mucho tiempo. Las fricciones entre Evo y Arce se profundizaban.<\/p>\n<p>\u00bfQu\u00e9 sucedi\u00f3 para que el tablero pol\u00edtico mudase tanto, de tal manera que pasaran de aparecer marchando juntos en noviembre de 2021, en \u201cdefensa del Gobierno\u201d, a estar enfrentados sin tregua, y, parad\u00f3jicamente, con otra marcha, pero, esta vez, liderada por Evo en contra de la gesti\u00f3n de Arce?<\/p>\n<p>Aqu\u00ed, un recuento de los conflictos que protagonizan Arce y Evo, en lo que se presenta como una relaci\u00f3n rota, quebrada desde hace dos a\u00f1os.<\/p>\n<p><span style=\"font-size:22px;\"><strong>DEL \u201cNO HABR\u00c1 OTRO GOLPE\u201d A LA QUEJA POR TV<\/strong><\/span> El 17 de abril de 2021, Arce y Evo aparec\u00edan juntos para advertir que no permitir\u00edan \u201cotro golpe\u201d. Se presentaban ante una concentraci\u00f3n en Cochabamba.\u00a0<\/p>\n<p>\u00abEstamos aqu\u00ed, en Cochabamba, para decir con absoluta claridad que la derecha golpista no pasar\u00e1\u00bb, avisaba el Dignatario, para luego aclarar que ni el odio ni la venganza son m\u00f3viles de las convicciones de su gobierno, sino el \u00e1nimo de encontrar justicia por los ca\u00eddos de 2019.<\/p>\n<p>Entonces, Morales a\u00fan sacaba cara por la gesti\u00f3n de quien fuera su ministro de Econom\u00eda. El exmandatario tambi\u00e9n dedicaba un mensaje. \u00abQueremos decirles a los golpistas, aqu\u00ed est\u00e1 el pueblo boliviano. Los vendepatrias nunca m\u00e1s volver\u00e1n\u201d.<\/p>\n<p>Ambos hablaban de unidad e identificaban a un \u00fanico \u201cenemigo\u201d: el gobierno de Jeanine \u00c1\u00f1ez. Lejos estaban los tiempos actuales de cargarle culpas a Arce: Evo coincid\u00eda en responsabilizar a Jeanine por la crisis econ\u00f3mica.<\/p>\n<p>Siete meses m\u00e1s tarde se dar\u00eda la segunda aparici\u00f3n conjunta. Ambos eran parte de una marcha con origen de partida en Caracollo, Oruro, y punto de llegada en La Paz.<\/p>\n<p>El 22 de noviembre se daba la denominada \u201cMarcha por la patria\u201d, con un Evo que regresaba a sus or\u00edgenes sindicales entre wiphalas, coca y cascos mineros. Junto a David Choquehuanca, vicepresidente del Estado, recorr\u00eda 188 kil\u00f3metros, tras arribar el 29 de noviembre a la sede de Gobierno.<\/p>\n<p>Tras esa pantalla proyectada hacia la sociedad, de unidad, Evo emit\u00eda una de sus primeras quejas en un acto en el que tambi\u00e9n participaban ambos. Era en septiembre de 2022, en una ceremonia por el mes aniversario de Cochabamba, cuando lamentaba que la estatal Bolivia TV cortara sus discursos.<\/p>\n<p>\u201cHermano Presidente, anticipadamente, quisiera pedirle con mucho respeto que el gerente de canal 7 no me corte las intervenciones. Tengo informaci\u00f3n permanente que las veces que participamos en su invitaci\u00f3n o por invitaci\u00f3n, no siempre, nos cortan. No es posible que se corte a algunos hermanos y hermanas del pueblo. Lo dijimos oportunamente que se evite esta forma de marginaci\u00f3n, hermano Presidente\u201d.<\/p>\n<p>Ante ello, Arce contestaba: \u201cYo quiero responder, tambi\u00e9n, a nuestro hermano Evo Morales para evitar cualquier susceptibilidad. Creo que lo que menos tenemos que generar es susceptibilidad entre nosotros mismos. Hay muchos intereses que nos quieren dividir y quieren generar dudas y peleas internamente (&#8230;). \u201cEn el (canal) 7.1 s\u00ed hay restricci\u00f3n para todos, no solamente para unos oradores. Se restringe porque es una transmisi\u00f3n en directo a trav\u00e9s de canales y hay restricci\u00f3n, por eso hay entre tres y ocho minutos que se transmite por alocuci\u00f3n. Por eso siempre se trata de ser breve, para que se le transmita todo y poder salir en transmisi\u00f3n\u201d.<\/p>\n<p><span style=\"font-size:22px;\"><strong>CELULAR<\/strong><\/span> Remont\u00e1ndonos antes del reclamo de Evo hacia Bolivia TV, se daba otro desencuentro con Arce, aunque no directo. Esto, despu\u00e9s de que el celular del l\u00edder azul fuera robado en medio de un acto pol\u00edtico en Santa Cruz, en agosto de 2022, y m\u00e1s tarde este acusara al ministro de Gobierno, Eduardo del Castillo, de haber estado presente cuando perpetraron la sustracci\u00f3n.<\/p>\n<p>\u201cPor favor, ministro de Gobierno, hermano Del Castillo, devu\u00e9lvamelo mi celular. No vas a encontrar nada, salvo que puedas montar algo\u201d, era la petici\u00f3n de Morales que m\u00e1s se replicaba en redes sociales y que incluso fue blanco de memes.<\/p>\n<p><span style=\"font-size:22px;\"><strong>\u201cPLAN NEGRO\u201d <\/strong><\/span>El 17 de septiembre de 2022, Evo dirig\u00eda uno de sus primeros dardos contra el gabinete del Dignatario, al denunciar que \u201cdesde alg\u00fan sector del Gobierno se elaboraba un plan negro\u201d para vincularlo con el tr\u00e1fico de drogas.<\/p>\n<p>\u201cNo importa que sigan implementando el plan negro. Lo verdaderamente importante es que se luche contra la corrupci\u00f3n y el encubrimiento del narcotr\u00e1fico\u201d, publicaba en su cuenta de X, generando dudas en torno a algunos ministros de Estado.<\/p>\n<p><span style=\"font-size:22px;\"><strong>\u201cCAJERO\u201d<\/strong><\/span> Un a\u00f1o m\u00e1s faltar\u00eda para que la interna entre las m\u00e1ximas figuras del MAS se viera desnudada. En septiembre del a\u00f1o pasado, Morales minimizaba las labores de Arce como ex ministro de Econom\u00eda reduci\u00e9ndolo a \u201ccajero\u201d. \u201cCreen que Lucho era el ide\u00f3logo del modelo econ\u00f3mico. En el gabinete, Lucho era conocido como cajero, no como ide\u00f3logo\u201d, dec\u00eda Evo.<\/p>\n<p>\u201cEst\u00e1 el tema que mencionaban del cajero, bueno. No tengo problema que me llamen como quieran, lo cierto es que los resultados son los que cuentan. Bolivia, desde que estuve como ministro de Econom\u00eda, ha estado con los mejores sitiales, con indicadores econ\u00f3micos y sociales, porque el modelo econ\u00f3mico social y productivo, que ha sido un modelo que se ha creado en la Universidad Mayor de San Andr\u00e9s, con dos profesores de la UMSA, los compa\u00f1eros Carlos Villegas y mi persona, hemos desarrollado todos los escritos\u201d, se atribu\u00eda Arce.<\/p>\n<p><span style=\"font-size:22px;\"><strong>EL HIJO DE ARCE<\/strong><\/span> En octubre de 2023, Evo apuntaba contra Marcelo Arce, hijo del Presidente. Denunciaba p\u00fablicamente un presunto \u201cnegocio familiar\u201d en el que, seg\u00fan \u00e9l, habr\u00edan participado el Mandatario y su hijo, con la gesti\u00f3n de recursos naturales como el litio y el gas.<\/p>\n<p>En conferencia de prensa, Evo aparec\u00eda con un audio en el que se o\u00eda: \u201cYo, cuando habl\u00e9 con Luis, me dijo: \u2018Hijo, yo ahora no tengo tiempo -as\u00ed me lo dijo- para ver los detalles, porque tengo que enfocarme en el tema pol\u00edtico, no quiero perderle el hilo\u2019\u201d.<\/p>\n<p>Expresaba sentirse \u201cdolido\u201d y sorprendido por el contenido de la escucha, que calific\u00f3 como \u201cmuy grave\u201d.<\/p>\n<p>Y seg\u00fan su versi\u00f3n, le habr\u00eda transmitido a Arce sus inquietudes de forma previa. \u00abUna vez hubo muchos comentarios sobre el hijo del Presidente. Estaba con Mar\u00eda Nela Prada, le dije: Presidente, la gente est\u00e1 hablando mucho de su hijo. Por favor, no s\u00e9 si sabr\u00e1, eso nos va a perjudicar. Me dijo: No se meta con mi familia\u00bb, contaba el excocalero, en entrevista con Piedra, Papel y Tinta, de La Raz\u00f3n.<\/p>\n<p><span style=\"font-size:22px;\"><strong>PRIMARIAS<\/strong><\/span> En septiembre de este a\u00f1o, con un doble liderazgo en disputa, Evo retaba a Arce a ir juntos a primarias abiertas, de modo que uno de los dos aceptara su victoria o derrota, de cara a las Elecciones Generales 2025.<\/p>\n<p>\u201cAcepto a Lucho primarias abiertas, todo para salvar a Bolivia \u00bfC\u00f3mo salvamos Bolivia de la situaci\u00f3n econ\u00f3mica? \u00bfSi viene convulsi\u00f3n total, se imaginan c\u00f3mo estar\u00eda Bolivia? El Gobierno no tiene ning\u00fan plan para salvar la situaci\u00f3n econ\u00f3mica. Entonces, priorizando bases, pasando por la elecci\u00f3n primaria abierta, desaf\u00edo, que el pueblo decida y vamos a las elecciones el pr\u00f3ximo a\u00f1o\u201d.<\/p>\n<p><span style=\"font-size:22px;\"><strong>\u201cAUTOGOLPE\u201d<\/strong><\/span> La revuelta militar del 26 de junio de este a\u00f1o, cuando tanques de guerra irrumpieron frente al Palacio Quemado comandados por Juan Jos\u00e9 Z\u00fa\u00f1iga, tambi\u00e9n los enfrent\u00f3. Evo pasaba de advertir un intento de golpe a acusar un \u201cautogolpe\u201d.<\/p>\n<p>Ahora, la batalla pol\u00edtica entre ambos se libra con una marcha liderada por Morales que pide el acortamiento de la gesti\u00f3n de Arce, a quien le cuelgan las responsabilidades por la escasez de d\u00f3lares, falta de combustible y el aumento de la canasta familiar.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.opinion.com.bo\/articulo\/pais\/evo-arce-divorcio-mas-mentor-pupilo-rina-2-anos\/20240922000036956235.html\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En julio de 2022, los rumores tomaban cierta fuerza: las rencillas entre el jefe de Estado, Luis Arce, y quien lo escogi\u00f3 entre sus hombres para que fuera su \u201csucesor\u201d, Evo Morales, ya exist\u00edan, aunque no se ventilaban medi\u00e1ticamente. Sin embargo, el excocalero se apresuraba para intentar derribar las teor\u00edas que apuntaban a sacar sobre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4062,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/bolivianoticia.com\/index.php\/wp-json\/wp\/v2\/posts\/4061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bolivianoticia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bolivianoticia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bolivianoticia.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bolivianoticia.com\/index.php\/wp-json\/wp\/v2\/comments?post=4061"}],"version-history":[{"count":0,"href":"https:\/\/bolivianoticia.com\/index.php\/wp-json\/wp\/v2\/posts\/4061\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bolivianoticia.com\/index.php\/wp-json\/wp\/v2\/media\/4062"}],"wp:attachment":[{"href":"https:\/\/bolivianoticia.com\/index.php\/wp-json\/wp\/v2\/media?parent=4061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bolivianoticia.com\/index.php\/wp-json\/wp\/v2\/categories?post=4061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bolivianoticia.com\/index.php\/wp-json\/wp\/v2\/tags?post=4061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}